{"id":15346,"date":"2022-05-25T10:12:12","date_gmt":"2022-05-25T08:12:12","guid":{"rendered":"https:\/\/norwegianmade.no\/markedsplass\/sotmosane\/"},"modified":"2025-06-09T21:59:10","modified_gmt":"2025-06-09T19:59:10","slug":"sotmosane","status":"publish","type":"product","link":"https:\/\/norwegianmade.no\/en\/produkt\/sotmosane\/","title":{"rendered":"S\u00f8tmosane"},"content":{"rendered":"<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oppskrift til S\u00f8tmosane strikka i S\u00f8lje, norsk pelsullgarn fr\u00e5 Hillesv\u00e5g ullvarefabrikk.\u00a0\u00a0<\/p>\n<p>Oppskrift sendt som pdf fil<\/p>\n","protected":false},"featured_media":15342,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[78,324,670,687],"product_tag":[],"class_list":{"0":"post-15346","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_vendor-mayasbutikk","7":"product_cat-gaver","8":"product_cat-jul","9":"product_cat-oppskrift","10":"product_cat-strikk-2","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-external"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00f8tmosane &#8226; Norwegian Made<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/norwegianmade.no\/produkt\/sotmosane\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00f8tmosane &#8226; Norwegian Made\" \/>\n<meta property=\"og:description\" content=\"Oppskrift til S\u00f8tmosane strikka i S\u00f8lje, norsk pelsullgarn fr\u00e5 Hillesv\u00e5g ullvarefabrikk.\u00a0\u00a0Oppskrift sendt som pdf fil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/norwegianmade.no\/produkt\/sotmosane\/\" \/>\n<meta property=\"og:site_name\" content=\"Norwegian Made\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T19:59:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/norwegianmade.no\/wp-content\/uploads\/2022\/05\/raud-hue1sk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/\",\"url\":\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/\",\"name\":\"S\u00f8tmosane &#8226; Norwegian Made\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/norwegianmade.no\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/raud-hue1sk.jpg\",\"datePublished\":\"2022-05-25T08:12:12+00:00\",\"dateModified\":\"2025-06-09T19:59:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/#primaryimage\",\"url\":\"https:\\\/\\\/norwegianmade.no\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/raud-hue1sk.jpg\",\"contentUrl\":\"https:\\\/\\\/norwegianmade.no\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/raud-hue1sk.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/produkt\\\/sotmosane\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/norwegianmade.no\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/norwegianmade.no\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00f8tmosane\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/#website\",\"url\":\"https:\\\/\\\/norwegianmade.no\\\/\",\"name\":\"Norwegian Made\",\"description\":\"Norges st\u00f8rste markedsplass for norske produsenter\",\"publisher\":{\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/norwegianmade.no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/#organization\",\"name\":\"Norwegian Made\",\"url\":\"https:\\\/\\\/norwegianmade.no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/norwegianmade.no\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo-liggende-norwegian-made-web.png\",\"contentUrl\":\"https:\\\/\\\/norwegianmade.no\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo-liggende-norwegian-made-web.png\",\"width\":200,\"height\":58,\"caption\":\"Norwegian Made\"},\"image\":{\"@id\":\"https:\\\/\\\/norwegianmade.no\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00f8tmosane &#8226; Norwegian Made","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/","og_locale":"en_US","og_type":"article","og_title":"S\u00f8tmosane &#8226; Norwegian Made","og_description":"Oppskrift til S\u00f8tmosane strikka i S\u00f8lje, norsk pelsullgarn fr\u00e5 Hillesv\u00e5g ullvarefabrikk.\u00a0\u00a0Oppskrift sendt som pdf fil","og_url":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/","og_site_name":"Norwegian Made","article_modified_time":"2025-06-09T19:59:10+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/norwegianmade.no\/wp-content\/uploads\/2022\/05\/raud-hue1sk.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/","url":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/","name":"S\u00f8tmosane &#8226; Norwegian Made","isPartOf":{"@id":"https:\/\/norwegianmade.no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/#primaryimage"},"image":{"@id":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/#primaryimage"},"thumbnailUrl":"https:\/\/norwegianmade.no\/wp-content\/uploads\/2022\/05\/raud-hue1sk.jpg","datePublished":"2022-05-25T08:12:12+00:00","dateModified":"2025-06-09T19:59:10+00:00","breadcrumb":{"@id":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/norwegianmade.no\/produkt\/sotmosane\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/#primaryimage","url":"https:\/\/norwegianmade.no\/wp-content\/uploads\/2022\/05\/raud-hue1sk.jpg","contentUrl":"https:\/\/norwegianmade.no\/wp-content\/uploads\/2022\/05\/raud-hue1sk.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/norwegianmade.no\/produkt\/sotmosane\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/norwegianmade.no\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/norwegianmade.no\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"S\u00f8tmosane"}]},{"@type":"WebSite","@id":"https:\/\/norwegianmade.no\/#website","url":"https:\/\/norwegianmade.no\/","name":"Norwegian Made","description":"Norges st\u00f8rste markedsplass for norske produsenter","publisher":{"@id":"https:\/\/norwegianmade.no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/norwegianmade.no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/norwegianmade.no\/#organization","name":"Norwegian Made","url":"https:\/\/norwegianmade.no\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/norwegianmade.no\/#\/schema\/logo\/image\/","url":"https:\/\/norwegianmade.no\/wp-content\/uploads\/2020\/11\/logo-liggende-norwegian-made-web.png","contentUrl":"https:\/\/norwegianmade.no\/wp-content\/uploads\/2020\/11\/logo-liggende-norwegian-made-web.png","width":200,"height":58,"caption":"Norwegian Made"},"image":{"@id":"https:\/\/norwegianmade.no\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/product\/15346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/comments?post=15346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/media\/15342"}],"wp:attachment":[{"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/media?parent=15346"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/product_brand?post=15346"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/product_cat?post=15346"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/norwegianmade.no\/en\/wp-json\/wp\/v2\/product_tag?post=15346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}